{"id":15476,"date":"2024-06-02T15:18:48","date_gmt":"2024-06-02T13:18:48","guid":{"rendered":"https:\/\/fdp-aktiv.de\/blog\/?p=15476"},"modified":"2024-06-02T15:18:48","modified_gmt":"2024-06-02T13:18:48","slug":"saarland-isringhaus-fordert-die-deaktivierung-der-website-des-bundes-klinik-atlas","status":"publish","type":"post","link":"https:\/\/fdp-aktiv.de\/blog\/2024\/06\/02\/saarland-isringhaus-fordert-die-deaktivierung-der-website-des-bundes-klinik-atlas\/","title":{"rendered":"Saarland &#8211; Isringhaus fordert die Deaktivierung der Website des Bundes-Klinik-Atlas"},"content":{"rendered":"<p>Angesichts der anhaltenden Kritik von Patienten, \u00c4rzten und Kliniken sowie der jetzt auch von der AWMF aufgezeigten M\u00e4ngel fordert die FDP Saar, den Bundes-Klinik-Atlas umgehend zu deaktivieren. Dazu Dr. Helmut Isringhaus, gesundheitspolitischer Sprecher der FDP Saar: \u201eDies soll die Nutzer vor falschen Ergebnissen und m\u00f6glichen gef\u00e4hrlichen Fehlleitungen sch\u00fctzen. Dar\u00fcber hinaus verlangen wir eine transparente Kommunikation \u00fcber alle vorgenommenen und geplanten \u00c4nderungen sowie in einer Beta-Version eine klare Darstellung des Versionsverlaufs.<\/p>\n<p>Die FDP Saar setzt sich f\u00fcr eine verl\u00e4ssliche und nutzerfreundliche Darstellung im Bundes-Klinik-Atlas ein, die das Vertrauen der B\u00fcrger in staatliche Informationsangebote st\u00e4rkt und die Gesundheit der Patientinnen und Patienten nicht gef\u00e4hrdet\u201c. Isring<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angesichts der anhaltenden Kritik von Patienten, \u00c4rzten und Kliniken sowie der jetzt auch von der AWMF aufgezeigten M\u00e4ngel fordert die FDP Saar, den Bundes-Klinik-Atlas umgehend zu deaktivieren. Dazu Dr. Helmut [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":12816,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[123],"tags":[707,708,4097],"class_list":["post-15476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit","tag-dr-helmut-isringhaus","tag-fdp-saar","tag-klinik-atlas"],"_links":{"self":[{"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/posts\/15476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/comments?post=15476"}],"version-history":[{"count":1,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/posts\/15476\/revisions"}],"predecessor-version":[{"id":15477,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/posts\/15476\/revisions\/15477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/media\/12816"}],"wp:attachment":[{"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/media?parent=15476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/categories?post=15476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/tags?post=15476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}