{"id":9341,"date":"2023-02-02T09:13:43","date_gmt":"2023-02-02T08:13:43","guid":{"rendered":"https:\/\/fdp-aktiv.de\/blog\/?p=9341"},"modified":"2023-02-02T09:13:43","modified_gmt":"2023-02-02T08:13:43","slug":"bundestag-koerner-die-eu-ist-nicht-opfer-sondern-ausloeser","status":"publish","type":"post","link":"https:\/\/fdp-aktiv.de\/blog\/2023\/02\/02\/bundestag-koerner-die-eu-ist-nicht-opfer-sondern-ausloeser\/","title":{"rendered":"Bundestag &#8211; K\u00d6RNER: Die EU ist nicht Opfer, sondern Ausl\u00f6ser"},"content":{"rendered":"<p>FDP-Pr\u00e4sidiumsmitglied Moritz K\u00f6rner schrieb f\u00fcr \u201eWelt Online\u201c den folgenden Gastbeitrag:<\/p>\n<figure id=\"attachment_9343\" aria-describedby=\"caption-attachment-9343\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/fdp-aktiv.de\/blog\/wp-content\/uploads\/2023\/02\/Profilbild-Moritz-Koerner.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-9343\" src=\"https:\/\/fdp-aktiv.de\/blog\/wp-content\/uploads\/2023\/02\/Profilbild-Moritz-Koerner-1024x1024.png\" alt=\"Moritz K\u00f6rner\" width=\"800\" height=\"800\" srcset=\"https:\/\/fdp-aktiv.de\/blog\/wp-content\/uploads\/2023\/02\/Profilbild-Moritz-Koerner-1024x1024.png 1024w, https:\/\/fdp-aktiv.de\/blog\/wp-content\/uploads\/2023\/02\/Profilbild-Moritz-Koerner-300x300.png 300w, https:\/\/fdp-aktiv.de\/blog\/wp-content\/uploads\/2023\/02\/Profilbild-Moritz-Koerner-150x150.png 150w, https:\/\/fdp-aktiv.de\/blog\/wp-content\/uploads\/2023\/02\/Profilbild-Moritz-Koerner-768x768.png 768w, https:\/\/fdp-aktiv.de\/blog\/wp-content\/uploads\/2023\/02\/Profilbild-Moritz-Koerner-1536x1536.png 1536w, https:\/\/fdp-aktiv.de\/blog\/wp-content\/uploads\/2023\/02\/Profilbild-Moritz-Koerner-400x400.png 400w, https:\/\/fdp-aktiv.de\/blog\/wp-content\/uploads\/2023\/02\/Profilbild-Moritz-Koerner.png 1585w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-9343\" class=\"wp-caption-text\">Moritz K\u00f6rner<\/figcaption><\/figure>\n<p>Die Pr\u00e4sidentin der Europ\u00e4ischen Kommission, Ursula von der Leyen, will mit einem neuen EU-Fonds auf den protektionistischen Inflation Reduction Act (IRA) der USA antworten. Dieser sogenannte EU-Souver\u00e4nit\u00e4tsfonds soll durch neue gemeinsame Schulden Subventionen in der EU finanzieren. Warum das aus liberaler Sicht der falsche Weg ist.<\/p>\n<p>Wir ernten, was wir s\u00e4en. Der Inflation Reduction Act ist nicht der Beginn einer protektionistischen US-<a href=\"https:\/\/fdp-aktiv.de\/blog\/2021\/01\/29\/fdp-forderung-wirtschaftspolitik\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"FDP Forderung Wirtschaftspolitik\" target=\"_blank\" rel=\"noopener\">Wirtschaftspolitik<\/a>, sondern die Gegenreaktion der Amerikaner auf die interventionistische EU-Politik der vergangenen Jahre.<\/p>\n<p>Als Biden 2021 sein Amt antrat, hatte die EU bereits knapp 600 Milliarden Euro f\u00fcr die Finanzierung des Europ\u00e4ischen Green Deals verplant \u2013 mit dem klaren Ziel, der europ\u00e4ischen Cleantechbranche durch Subventionen unter die Arme zu greifen. Wenn man die nationalen Subventionen der Mitgliedstaaten dazurechnet, sind die in zehn Jahren auszugebenden 369 Milliarden US-Dollar der Amerikaner bestenfalls Peanuts dagegen.<\/p>\n<p>Auch die protektionistischen Ansiedlungsanforderungen des neuen US-Gesetzes k\u00f6nnen nicht unabh\u00e4ngig von der geplanten europ\u00e4ischen CO2-Grenzsteuer gesehen werden, mit der die EU ihre Unternehmen vor der g\u00fcnstigeren, weniger klimabewussten Konkurrenz aus Drittstaaten sch\u00fctzen m\u00f6chte.<\/p>\n<p>Die EU ist entsprechend nicht Opfer, sondern ein Ausl\u00f6ser der neuen amerikanischen Subventionspolitik. Eine Subventionspolitik, von der wir als Freihandelspartner der USA heute im \u00dcbrigen nicht negativ betroffen w\u00e4ren, h\u00e4tten deutsche Chlorhuhn-Angstmacher die EU-US-Freihandelsvertragsverhandlungen vor Jahren nicht absichtlich zu Fall gebracht. Wenn wir eine Ver\u00e4nderung bei den Amerikanern erwirken wollen, sollten wir deshalb zun\u00e4chst vor der eigenen T\u00fcre kehren.<\/p>\n<p>Wer die US-<a href=\"https:\/\/fdp-aktiv.de\/blog\/2021\/01\/29\/fdp-forderung-wirtschaftspolitik\/\" data-internallinksmanager029f6b8e52c=\"10\" title=\"FDP Forderung Wirtschaftspolitik\" target=\"_blank\" rel=\"noopener\">Wirtschaftspolitik<\/a> nun als Vorwand nutzt, um zus\u00e4tzliche EU-Subventionen zu fordern, heizt den negativen Protektionismus-Wettlauf nur weiter an und besch\u00e4digt damit nachhaltig die freihandelsbasierte globale Marktwirtschaft, der Deutschland seinen Wohlstand verdankt.<\/p>\n<p>Es w\u00e4re Selbstmord aus Angst vor dem Tod. Wir d\u00fcrfen unsere marktwirtschaftlichen Prinzipien nicht aufs Spiel setzen. Eine staatsinterventionistische Subventionswirtschaft ist kein Zukunftsmodell, sondern ein Gesch\u00e4ftsmodell f\u00fcr den \u00f6konomischen Untergang.<\/p>\n<p>Statt in einen ruin\u00f6sen Abschottungs- und Subventionswettkampf einzutreten, muss die EU ihre Politik darauf konzentrieren, die Globalisierung voranzubringen und neue Handelsvertr\u00e4ge abzuschlie\u00dfen. Ein Binnenmarkt mit knapp 450 Millionen Einwohnern hat genug Marktmacht, um die bestehenden Regeln der internationalen Handels- und Wirtschaftsbeziehungen durchzusetzen.<\/p>\n<p>Die EU braucht keine weiteren Geldt\u00f6pfe. Die erw\u00e4hnten Green-Deal-Gelder sind nicht nur nicht ausgesch\u00f6pft, sondern von zahlreichen Mitgliedstaaten noch nicht einmal angezapft worden. Nur ein Bruchteil der bereitgestellten Corona-Wiederaufbaugelder wurde bis jetzt \u00fcberwiesen und auch der Gro\u00dfteil der Strukturmittel aus dem aktuellen EU-Haushalt bleibt seit zwei Jahren de facto ungenutzt.<\/p>\n<p>Es ist also nicht nur genug, sondern mehr Geld als gebraucht wird vorhanden. Die daraus langfristig resultierende \u00dcberf\u00f6rderung ist Gift f\u00fcr die Wirtschaft. Ein mit Staatshilfen aufgepumpter EU-Markt wird ineffiziente Betriebe im Markt halten, kostensenkende Innovationen behindern und damit einen desastr\u00f6sen Inflationsturbo entfachen.<\/p>\n<p>Das Ergebnis w\u00e4ren langfristige Wettbewerbsnachteile f\u00fcr europ\u00e4ische Unternehmen und signifikante Wohlstandsverluste f\u00fcr europ\u00e4ische Konsumenten. Wer verhindern m\u00f6chte, dass europ\u00e4ische Cleantechunternehmer irgendwann, \u00e4hnlich wie manche Landwirte, zwei Drittel ihres Einkommens aus Subventionen beziehen, m\u00f6ge deshalb rechtzeitig die Budget-Rei\u00dfleine ziehen. Die deutsche Solarbranche ist schon einmal an falscher Subventionspolitik zu Grunde gegangen.<\/p>\n<p>Allein zwischen 2019 und 2021 ist der Schuldenstand der EU-Mitgliedstaaten um 1885 Milliarden Euro angestiegen. Die Einnahmenseite der bestehenden EU-Schuldent\u00f6pfe ist bis heute nicht endg\u00fcltig gekl\u00e4rt. Die Zinsen f\u00fcr EU-Anleihen wachsen rasant.<\/p>\n<p>Ein relevanter Teil der EU-Anleihen zur Finanzierung des Coronawiederaufbaufonds geht an Gl\u00e4ubiger au\u00dferhalb der EU. In solch schwierigen Zeiten werden neue EU-Schulden die Handlungsf\u00e4higkeit zuk\u00fcnftiger Generationen erheblich beschr\u00e4nken und die EU abh\u00e4ngiger von internationalen Geldgebern machen.<\/p>\n<p>Unter diesen Umst\u00e4nden beim neuen EU-Schuldentopf von einem \u201eSouver\u00e4nit\u00e4tsfonds\u201c zu sprechen, ist so falsch, dass nicht mal das Gegenteil richtig ist. Die Schuldenunion ist ein rechtlicher und \u00f6konomischer Irrweg, es br\u00e4uchte mehr Reformmut.<\/p>\n<p>Eine mutigere Ursula von der Leyen k\u00f6nnte zum Beispiel einen Teil des ben\u00f6tigten Geldes diesmal nicht komplett der k\u00fcnftigen Generation, sondern ein wenig den K\u00fchen wegnehmen und die landwirtschaftlichen Betriebe dabei unterst\u00fctzen, schrittweise unabh\u00e4ngig von F\u00f6rdermitteln zu werden.<\/p>\n<p>EU-Kommissionsbeamte k\u00f6nnten beauftragt werden, mehr B\u00fcrokratie abzubauen als sie kreieren. Die Mitgliedstaaten k\u00f6nnten verlangen, die Subventionskapazit\u00e4t der EU-Mittel beizubehalten, aber die Budgetflexibilit\u00e4tsregeln auszuweiten, um Forschung und Entwicklung zum gr\u00f6\u00dften Posten des EU-Haushalts zu machen.<\/p>\n<p>Also vereinfacht gesprochen: Die EU sollte sich mehr auf Biotech als auf Biomilch konzentrieren und zuk\u00fcnftig die Erm\u00f6glichung von Technologievorspr\u00fcngen und nicht die Subventionierung von Technologier\u00fcckst\u00e4nden zum Herzst\u00fcck ihrer Haushaltspolitik machen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FDP-Pr\u00e4sidiumsmitglied Moritz K\u00f6rner schrieb f\u00fcr \u201eWelt Online\u201c den folgenden Gastbeitrag: Die Pr\u00e4sidentin der Europ\u00e4ischen Kommission, Ursula von der Leyen, will mit einem neuen EU-Fonds auf den protektionistischen Inflation Reduction Act [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,173],"tags":[455,852],"class_list":["post-9341","post","type-post","status-publish","format-standard","hentry","category-aussenpolitik","category-podcast","tag-gastbeitrag","tag-moritz-koerner"],"_links":{"self":[{"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/posts\/9341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/comments?post=9341"}],"version-history":[{"count":2,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/posts\/9341\/revisions"}],"predecessor-version":[{"id":9344,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/posts\/9341\/revisions\/9344"}],"wp:attachment":[{"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/media?parent=9341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/categories?post=9341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fdp-aktiv.de\/blog\/wp-json\/wp\/v2\/tags?post=9341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}